
  {"id":243031,"date":"2024-05-30T12:20:04","date_gmt":"2024-05-30T10:20:04","guid":{"rendered":"https:\/\/www.cabasse.com\/?page_id=243031"},"modified":"2026-01-20T11:12:02","modified_gmt":"2026-01-20T10:12:02","slug":"the-pearl-myuki-fr","status":"publish","type":"page","link":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/","title":{"rendered":"THE PEARL MYUKI"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2022\/11\/Bande-noire.png\u00a0\u00bb custom_padding=\u00a0\u00bb20px||11px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb10px|auto|11px|auto||\u00a0\u00bb custom_padding=\u00a0\u00bb11px||7px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/Myuki-Banniere.png\u00a0\u00bb title_text=\u00a0\u00bbMyuki Banniere\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/05\/High-Resolution-Connected-Speaker-3-1.png\u00a0\u00bb title_text=\u00a0\u00bbHigh Resolution Connected Speaker (3) (1)\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; specialty=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb78px|49px|0px|48px|false|\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb60px||60px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_wc_images product=\u00a0\u00bb242026&Prime; show_sale_badge=\u00a0\u00bboff\u00a0\u00bb sale_badge_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb|||21px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; specialty_columns=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|34px||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_wc_title product=\u00a0\u00bb242026&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_title][et_pb_wc_description product=\u00a0\u00bb242026&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb-15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_description][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/FR-Myuki-Picto.png\u00a0\u00bb title_text=\u00a0\u00bbFR Myuki Picto\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_scale=\u00a0\u00bb138%|138%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-7px||2px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_wc_price product=\u00a0\u00bb31491&Prime; _builder_version=\u00a0\u00bb4.16&Prime; body_font_size=\u00a0\u00bb28px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_price][et_pb_divider color=\u00a0\u00bbrgba(0,0,0,0.13)\u00a0\u00bb divider_weight=\u00a0\u00bb2px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-7px||2px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_wc_add_to_cart product=\u00a0\u00bb242026&Prime; show_quantity=\u00a0\u00bboff\u00a0\u00bb show_stock=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_add_to_cart][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/magasins\/\u00a0\u00bb button_text=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_phone=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb19px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb|27px||27px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|16px||16px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_border_width_tablet=\u00a0\u00bb2px\u00a0\u00bb button_border_width_phone=\u00a0\u00bb\u00a0\u00bb button_border_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb#specificationstpp\u00a0\u00bb button_text=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_phone=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bb\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|34px||34px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|42px||42px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; specialty=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb78px|49px|0px|48px|false|\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb60px||60px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_wc_images product=\u00a0\u00bb242026&Prime; show_sale_badge=\u00a0\u00bboff\u00a0\u00bb sale_badge_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb|||21px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; specialty_columns=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_wc_add_to_cart product=\u00a0\u00bb242026&Prime; show_quantity=\u00a0\u00bboff\u00a0\u00bb show_stock=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_add_to_cart][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|34px||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_wc_title product=\u00a0\u00bb242026&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_title][et_pb_wc_description product=\u00a0\u00bb242026&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; text_orientation=\u00a0\u00bbjustified\u00a0\u00bb custom_margin=\u00a0\u00bb-15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_description][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/Pic-SQ-Myuki-FR.png\u00a0\u00bb title_text=\u00a0\u00bbPic SQ Myuki FR\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/magasins\/\u00a0\u00bb button_text=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_phone=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb19px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb|27px||27px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|16px||16px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_border_width_tablet=\u00a0\u00bb2px\u00a0\u00bb button_border_width_phone=\u00a0\u00bb\u00a0\u00bb button_border_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_button button_url=\u00a0\u00bb#specificationstpp\u00a0\u00bb button_text=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_phone=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bb\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|34px||34px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|42px||42px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_wc_price product=\u00a0\u00bb31491&Prime; _builder_version=\u00a0\u00bb4.16&Prime; body_font_size=\u00a0\u00bb28px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_wc_price][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/Design-sans-titre-2025-04-24T101506.641-1.png\u00a0\u00bb title_text=\u00a0\u00bbDesign sans titre &#8211; 2025-04-24T101506.641 (1)\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb80px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb||28px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; module_class=\u00a0\u00bbinverse\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb12px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb header_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #000000;\">UN RAPPORT COMPACIT\u00c9 \/ PERFORMANCES ACOUSTIQUES D\u2019EXCEPTION<\/span><\/h1>\n<p style=\"text-align: justify;\">[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">UN RAPPORT COMPACIT\u00c9 \/ PERFORMANCES ACOUSTIQUES D\u2019EXCEPTION<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb min_height=\u00a0\u00bb134.8px\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb48px||3px|||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"color: #000000;\">Ultra compacte, cette nouvelle enceinte Cabasse est dot\u00e9e d\u2019un son \u00e0 la fois tr\u00e8s \u00e9quilibr\u00e9 et tr\u00e8s puissant gr\u00e2ce notamment \u00e0 ses nouveaux haut-parleurs capables de jouer jusqu\u2019\u00e0 109 dB en st\u00e9r\u00e9o :<\/span><\/p>\n<p><span style=\"color: #000000;\">Un haut-parleur large bande DOM 45 et 2 haut-parleurs de grave de 12 cm \u00e0 membrane structure alv\u00e9ol\u00e9e de type nid d&rsquo;abeille en disposition Push Push fonctionnant dans un volume de charge tr\u00e8s r\u00e9duit, pour des basses pr\u00e9sentes, fermes et tendues.<\/span><\/p>\n<p><span style=\"color: #000000;\">De nouveaux hauts parleurs qui surprendront les utilisateurs par leur impact et profondeur.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/360_MYUKI_WH_WHbg_square.hevc_.mp4&Prime; src_webm=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/360_MYUKI_WH_WHbg_square.webm\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb module_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb module_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb37px||37px||true|\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb module_class=\u00a0\u00bbinverse\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb26px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">UNE ENCEINTE ACTIVE CONNECT\u00c9E HAUTE R\u00c9SOLUTION ULTRA COMPL\u00c8TE<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">UNE ENCEINTE ACTIVE CONNECT\u00c9E HAUTE R\u00c9SOLUTION ULTRA COMPL\u00c8TE<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Utilisation mono ou st\u00e9r\u00e9o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vous pouvez disposer de cette enceinte en mono (99 dB RMS), ou choisir d\u2019en jumeler deux\u00a0 pour\u00a0 profiter du son st\u00e9r\u00e9o Cabasse (109 dB cr\u00eate st\u00e9r\u00e9o).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Multi-sources, elle est adapt\u00e9e pour la diffusion sur TV, Platines, Lecteur CD ou NAS.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Batterie ultra performante jusqu\u2019\u00e0 12 heures d\u2019autonomie pour profiter du son Cabasse o\u00f9 que vous alliez.<\/span><\/p>\n<p><span style=\"color: #000000;\">L&rsquo;enceinte b\u00e9n\u00e9ficie du Smart Wi-Fi pour une optimisation automatique du r\u00e9seau sans coupure musicale.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/myuki-side.png\u00a0\u00bb title_text=\u00a0\u00bbmyuki &#8211; side\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_scale=\u00a0\u00bb110%|110%\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/Myuki-and-case.hevc_1.mp4&Prime; src_webm=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/Myuki-and-case.mp4&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0UNE ENCEINTE LUXUEUSE ET RAFFIN\u00c9E POUR TOUTES LES OCCASIONS<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">UNE ENCEINTE LUXUEUSE ET RAFFIN\u00c9E POUR TOUTES LES OCCASIONS\u00a0<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Avec son design lifestyle, aux formes arrondies, THE PEARL MYUKI, est une enceinte bijou \u00e9l\u00e9gante, qui s\u2019int\u00e8gre dans tout type d\u2019int\u00e9rieur : elle est disponible en finition noir mat ou blanc mat avec des enjoliveurs et d\u00e9tails chrom\u00e9s (noirs ou argent\u00e9s) et une Lissajous, emboss\u00e9e dans les woofers.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">THE PEARL MYUKI (17 cm de diam\u00e8tre pour environ 2 kilos) se d\u00e9place facilement de pi\u00e8ce en pi\u00e8ce gr\u00e2ce \u00e0 sa poign\u00e9e discr\u00e8te int\u00e9gr\u00e9e.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Transportable ais\u00e9ment gr\u00e2ce \u00e0 son sac sur-mesure et sa bandouli\u00e8re, THE PEARL MYUKI vous permettra d&rsquo;\u00e9couter un son de qualit\u00e9, puissant et pur o\u00f9 que vous alliez.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/eclate-1.png\u00a0\u00bb title_text=\u00a0\u00bb\u00e9clat\u00e9\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb37px||37px||true|\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb module_id=\u00a0\u00bbdiscret\u00a0\u00bb module_class=\u00a0\u00bbinverse\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\"><\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\"><\/span><\/h3>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">ERGONOMIE<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">ERGONOMIE<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"color: #000000;\">THE PEARL MYUKI dispose sur sa partie sup\u00e9rieure de 6 touches tactiles LED lumineuses dot\u00e9es d\u2019un l\u00e9ger retour haptique* pour faciliter son contr\u00f4le (source \/ play pause \/ volume \/ allumer \u2013 \u00e9teindre).<\/span><\/p>\n<p><span style=\"color: #000000;\">Une poign\u00e9e discr\u00e8te est int\u00e9gr\u00e9e pour faciliter la prise en main.<\/span><\/p>\n<p><span style=\"color: #000000;\">*vibration<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/360_MYUKI_BK_WHbg_square.hevc_.mp4&Prime; src_webm=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/360_MYUKI_BK_WHbg_square.webm\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/multoroomm-photo.png\u00a0\u00bb title_text=\u00a0\u00bbmultoroomm photo\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0THE PEARL MYUKI COMPATIBLE AVEC TOUS LES SYST\u00c8MES CONNECT\u00c9S CABASSE\u00a0!<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">THE PEARL MYUKI COMPATIBLE AVEC TOUS LES SYST\u00c8MES CONNECT\u00c9S CABASSE !<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Pour disposer d\u2019un son haut de gamme dans toutes les pi\u00e8ces de la maison, les utilisateurs peuvent grouper THE PEARL MYUKI avec d\u2019autres syst\u00e8mes connect\u00e9s Cabasse dont notamment la gamme lifestyle THE PEARL COLLECTION ou CLASSIQUE CONNECT\u00c9.<span style=\"font-size: 18px;\"> Les syst\u00e8mes Cabasse peuvent \u00eatre coupl\u00e9s et contr\u00f4l\u00e9s ais\u00e9ment via l\u2019application unique StreamCONTROL ou avec Airplay 2.<\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_video_mp4=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/Video-Myuki.hevc_.mp4&Prime; background_video_webm=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/Video-Myuki.webm\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/09\/trans.png\u00a0\u00bb title_text=\u00a0\u00bbtrans\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb35px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb11px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0UN SYST\u00c8ME \u00c9L\u00c9GANT ADAPT\u00c9 \u00c0 VOTRE INT\u00c9RIEUR<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">UN SYST\u00c8ME \u00c9L\u00c9GANT ADAPT\u00c9 \u00c0 VOTRE INT\u00c9RIEUR<\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb13px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/m2.png\u00a0\u00bb title_text=\u00a0\u00bbm2&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/sq-myuki.jpg\u00a0\u00bb title_text=\u00a0\u00bbsq myuki\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0LE SON HAUTE RESOLUTION<br \/>AU BOUT DES DOIGTS<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">LE SON HAUTE RESOLUTION<br \/>AU BOUT DES DOIGTS<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb99.6%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb|67px||||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019application StreamCONTROL vous propose un panel complet de services de streaming haute r\u00e9solution, compatibles avec les assistants vocaux et de nombreuses options de contr\u00f4le et de r\u00e9glages sur-mesure. Parcourez toute votre musique, vos podcasts, vos radios et vos livres audio au sein d\u2019une seule application propri\u00e9taire.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/App-.png\u00a0\u00bb title_text=\u00a0\u00bbApp-\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||0px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; module_class=\u00a0\u00bbinverse\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/iOS-1.png\u00a0\u00bb title_text=\u00a0\u00bbiOS (1)\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|||0px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0CONFIGURATION SIMPLE ET RAPIDE<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">CONFIGURATION SIMPLE ET RAPIDE<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb99.6%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb|67px||||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Allumez votre enceinte, ouvrez l&rsquo;application et laissez-et quelques etapes dans le processus d&rsquo;installaion.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/magasins\/\u00a0\u00bb button_text=\u00a0\u00bbt\u00e9l\u00e9chargez l&rsquo;application\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_phone=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb19px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb|27px||27px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|16px||16px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_border_width_tablet=\u00a0\u00bb2px\u00a0\u00bb button_border_width_phone=\u00a0\u00bb\u00a0\u00bb button_border_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0G\u00c9REZ VOTRE \u00c9COSYST\u00c8ME CABASSE GR\u00c2CE AU MULTI-ROOM<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">G\u00c9REZ VOTRE \u00c9COSYST\u00c8ME CABASSE GR\u00c2CE AU MULTI-ROOM<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb99.6%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb|67px||||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">G\u00e9rez plusieurs zones d\u2019\u00e9coute que vous pouvez renommer en fonction de la pi\u00e8ce dans laquelle se trouve votre syst\u00e8me Cabasse.<\/span><\/p>\n<p><span style=\"color: #000000;\">Gr\u00e2ce au menu qui affiche la zone :<\/span><br \/><span style=\"color: #000000;\">Basculez facilement entre vos zones d\u2019\u00e9coute,<\/span><\/p>\n<p><span style=\"color: #000000;\">Visualisez les zones disponibles en multi-room,<\/span><\/p>\n<p><span style=\"color: #000000;\">Regroupez, rajoutez ou supprimez vos syst\u00e8mes Cabasse par zone.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/multoroomm-photo.png\u00a0\u00bb title_text=\u00a0\u00bbmultoroomm photo\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/stereo.png\u00a0\u00bb title_text=\u00a0\u00bbstereo\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb80%\u00a0\u00bb border_radii=\u00a0\u00bbon|17px|17px|17px|17px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0COMBINEZ DEUX PEARL MYUKI EN ST\u00c9R\u00c9O<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">COMBINEZ DEUX PEARL MYUKI EN ST\u00c9R\u00c9O<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/Stereo-Myuki-1.png\u00a0\u00bb title_text=\u00a0\u00bbStereo Myuki\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb48%\u00a0\u00bb border_radii=\u00a0\u00bbon|17px|17px|17px|17px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/magasins\/\u00a0\u00bb button_text=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_phone=\u00a0\u00bbEcoutez en magasin\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb19px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb|27px||27px|false|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|16px||16px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_border_width_tablet=\u00a0\u00bb2px\u00a0\u00bb button_border_width_phone=\u00a0\u00bb\u00a0\u00bb button_border_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb37px||37px||true|\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb module_class=\u00a0\u00bbinverse\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0ACCESSOIRE FIXATION\u00a0<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">ACCESSOIRE FIXATION !<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">THE PEARL MYUKI peut \u00e9galement \u00eatre fix\u00e9e au mur avec un support mural Cabasse compatible.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/04\/Myuki-accessoire.png\u00a0\u00bb title_text=\u00a0\u00bbMyuki accessoire\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb80%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_video_mp4=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/05\/SIDETOPvibes_MYUKI_WH6_WHbg-2.mp4&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/04\/trans-2560-1321.png\u00a0\u00bb title_text=\u00a0\u00bbtrans 2560-1321&Prime; disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; custom_padding=\u00a0\u00bb20px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb12px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb min_height=\u00a0\u00bb134.8px\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb48px|97px|3px|157px||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Pour \u00e9couter un son de qualit\u00e9 chez soi ou en voyage, THE PEARL MYUKI dispose \u00e9galement des meilleures technologies int\u00e9gr\u00e9es dans les syst\u00e8mes haut de gamme Cabasse :\u00a0<\/span><\/p>\n<p style=\"text-align: center;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb header_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u00a0r\u00e9glage DFE<\/span><\/h1>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">R\u00c9GLAGE DFE<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Le DFE est un mode qui maximise la puissance en temps r\u00e9el envoy\u00e9e aux haut-parleurs selon le niveau d\u2019\u00e9coute, du contenu spectral et de la dynamique du morceau. Cette technologie permet d&rsquo;\u00e9couter \u00e0 bas volume sans compromettre la qualit\u00e9 d&rsquo;\u00e9coute et la dynamique des morceaux.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb header_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Calibration automatique de salle CRCS<\/span><\/h1>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">CALIBRATION AUTOMATIQUE DE SALLE CRCS<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Comme dans les syst\u00e8mes les plus sophistiqu\u00e9s Cabasse tels que La Sph\u00e8re, THE PEARL MYUKI poss\u00e8de un syst\u00e8me brevet\u00e9 de correction automatique de salle avec micro int\u00e9gr\u00e9 dans l&rsquo;enceinte pour une acoustique optimale quel que soit le lieu d\u2019\u00e9coute.<\/span><\/p>\n<p><span style=\"color: #ffffff; font-size: x-large;\"><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb20px\u00a0\u00bb header_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb width=\u00a0\u00bb75%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">R\u00e9glage du spectre tonal<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">R\u00c9GLAGE DU SPECTRE TONAL<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.17.1&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Pour un son sur-mesure\u00a0 selon ses go\u00fbts<\/span><\/p>\n<p><span style=\"color: #ffffff; font-size: x-large;\"><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb32px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2022\/09\/2560px-Qobuz_logotype.svg.png\u00a0\u00bb title_text=\u00a0\u00bb2560px-Qobuz_logotype.svg\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb21%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; text_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb text_font_size=\u00a0\u00bb28px\u00a0\u00bb header_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb28px\u00a0\u00bb module_alignment=\u00a0\u00bbleft\u00a0\u00bb custom_margin=\u00a0\u00bb35px||36px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Profitez de la meilleure qualit\u00e9 de son sur vos enceintes Cabasse !<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">PROFITEZ DE LA MEILLEURE QUALIT\u00c9 DE SON SUR VOS ENCEINTES CABASSE !<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/offre-qobuz\/\u00a0\u00bb button_text=\u00a0\u00bbTester Qobuz\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_border_radius=\u00a0\u00bb4px\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb-8px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/04\/myuki_pm2-2.jpg\u00a0\u00bb title_text=\u00a0\u00bbmyuki_pm2 (2)\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb22%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; module_id=\u00a0\u00bbspecifications\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; background_color=\u00a0\u00bb#000000&Prime; height=\u00a0\u00bb690px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-60px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb14px|31px|37px|31px||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb46px|auto||auto|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb38px||34px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text content_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb module_id=\u00a0\u00bbspecificationstpp\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb text_text_color=\u00a0\u00bbrgba(0,0,0,0.39)\u00a0\u00bb text_font_size=\u00a0\u00bb36px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Caract\u00e9ristiques &amp; Sp\u00e9cifications<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">CARACTERISTIQUES &amp; SPECIFICATIONS<\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb10px|auto|15px|auto|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb17px||0px|||\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_toggle title=\u00a0\u00bbSON\u00a0\u00bb open_toggle_text_color=\u00a0\u00bb#000000&Prime; icon_color=\u00a0\u00bb#000000&Prime; open_icon_color=\u00a0\u00bb#000000&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; title_text_color=\u00a0\u00bb#000000&Prime; title_level=\u00a0\u00bbh3&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb closed_title_font_size=\u00a0\u00bb18px\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Syst\u00e8me st\u00e9r\u00e9o<br \/>Volume sonore max 109 dB cr\u00eate st\u00e9r\u00e9o<br \/>Bande passante 30 \u2013 23 000 Hz<br \/>Haut-parleurs par enceinte : Medium-tweeter DOM 45<br \/>Woofer 2 x 12 cm<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbCONNECTIVIT\u00c9\u00a0\u00bb open_toggle_text_color=\u00a0\u00bb#000000&Prime; icon_color=\u00a0\u00bb#000000&Prime; open_icon_color=\u00a0\u00bb#000000&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; title_text_color=\u00a0\u00bb#000000&Prime; title_level=\u00a0\u00bbh3&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_margin=\u00a0\u00bb-30px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h4>Connectivit\u00e9<\/h4>\n<p>Connectivit\u00e9 : Ethernet \u2013 WiFi \u2013 Bluetooth \u2013 Optique SPDIF \u2013 Analogique RCA \u2013 USB \u2013 Prise TV<\/p>\n<p>Port link pour relier les 2 enceintes en optique en cas de faible d\u00e9bit internet.<\/p>\n<h4>Formats audio<\/h4>\n<p>Formats pris en charge MP3 &#8211; AAC -WMA &#8211; AIFF &#8211; FLAC \u2013 ALAC &#8211; Ogg- Vorbis &#8211; DSD 64\/128 &#8211; WMA lossless<\/p>\n<p>Calibration automatique<\/p>\n<p>Multi room Haute R\u00e9solution<\/p>\n<h4>Services de musique en ligne<\/h4>\n<p><a href=\"https:\/\/www.cabasse.com\/wp-content\/uploads\/2026\/01\/Picto-music-spec.jpg\"><\/a><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cabasse.com\/wp-content\/uploads\/2026\/01\/Picto-music-spec.jpg\" width=\"1024\" height=\"46\" alt=\"\" class=\"wp-image-34561 alignnone size-large\" \/><\/p>\n<h4>Compatibilit\u00e9<\/h4>\n<p><a href=\"https:\/\/cabasse.happyfox.com\/kb\/article\/66-compatibilit%C3%A9-google-home\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cabasse.com\/wp-content\/uploads\/2021\/12\/hey-google-small.png\" alt=\"\" class=\"wp-image-36673 alignnone size-full\" width=\"216\" height=\"68\" \/><\/a><\/p>\n<p>&nbsp;[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbDIMENSIONS\u00a0\u00bb open_toggle_text_color=\u00a0\u00bb#000000&Prime; icon_color=\u00a0\u00bb#000000&Prime; open_icon_color=\u00a0\u00bb#000000&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; title_text_color=\u00a0\u00bb#000000&Prime; title_level=\u00a0\u00bbh3&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_margin=\u00a0\u00bb-30px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Dimension: 186 x 174 x 180 mm<\/p>\n<p>Poids : 2.1 kilos<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbACCESSOIRE INCLUS\u00a0\u00bb open_toggle_text_color=\u00a0\u00bb#000000&Prime; icon_color=\u00a0\u00bb#000000&Prime; open_icon_color=\u00a0\u00bb#000000&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; title_text_color=\u00a0\u00bb#000000&Prime; title_level=\u00a0\u00bbh3&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_margin=\u00a0\u00bb-30px||40px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Sac de transport<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbGUIDE UTILISATEUR\u00a0\u00bb open_toggle_text_color=\u00a0\u00bb#000000&Prime; icon_color=\u00a0\u00bb#000000&Prime; open_icon_color=\u00a0\u00bb#000000&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; title_text_color=\u00a0\u00bb#000000&Prime; title_level=\u00a0\u00bbh3&Prime; title_font=\u00a0\u00bb|600|||||||\u00a0\u00bb title_font_size=\u00a0\u00bb18px\u00a0\u00bb title_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_margin=\u00a0\u00bb-30px||40px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><a href=\"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/06\/Manual_PEARL_MYUKI_v4.pdf\">Notice utilisateur THE PEARL MYUKI<\/a><\/p>\n<p><a href=\"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/05\/MYUKI_Leaflet_21x21_VF.pdf\">Fiche technique THE PEARL MYUKI<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||24px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb10px||-25px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb12px||12px||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0LA PRESSE EN PARLE<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">LA PRESSE EN PARLE<\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/08\/Notation-On-Mag-TPM.jpg\u00a0\u00bb title_text=\u00a0\u00bbNotation On Mag TPM\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|149px||-60px|true|false\u00a0\u00bb custom_padding=\u00a0\u00bb25px|0px||0px||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: left;\"><span style=\"color: #000000;\">ON Mag : 4\/4 \u00e9toiles pour THE PEARL MYUKI.<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb17px\u00a0\u00bb text_line_height=\u00a0\u00bb1.4em\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div class=\"\" data-block=\"true\" data-editor=\"4fr8e\" data-offset-key=\"9cdll-0-0\">\n<div data-offset-key=\"9cdll-0-0\" class=\"_1mf _1mj\">\n<p><em><span style=\"color: #000000;\">\u00ab L\u2019enceinte Cabasse The Pearl Myuki permet \u00e0 la marque fran\u00e7aise de d\u00e9velopper une offre compl\u00e8te en termes d\u2019enceintes connect\u00e9es. Ce nouveau mod\u00e8le fonctionnant sur batterie permet un usage aussi bien en int\u00e9rieur qu&rsquo;en dehors de la maison, selon les envies&#8230; \u00bb.<\/span><\/em><\/p>\n<p><em><span style=\"color: #000000;\">\u00ab Cette enceinte hybride plaira \u00e0 ceux qui attendent un son avec \u00e0 la fois de la chaleur dans le m\u00e9dium et de l\u2019impact dans le grave. La qualit\u00e9 globale est r\u00e9solument premium, bien sup\u00e9rieure \u00e0 celle des enceintes nomades Bluetooth les plus courantes \u00bb.<\/span><\/em><\/p>\n<p><span style=\"color: #000000;\">Pour consulter l&rsquo;article en int\u00e9gralit\u00e9, cliquez<\/span> <a href=\"https:\/\/www.on-mag.fr\/index.php\/topaudio\/tests-auditions\/26394-test-cabasse-the-pearl-myuki-une-enceinte-nomade-wifi-bluetooth-au-son-chaleureux\">ICI<\/a>.<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb27px||27px||true|\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-20px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb48px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/11\/Design-sans-titre-2025-11-06T112123.842.png\u00a0\u00bb title_text=\u00a0\u00bbDesign sans titre &#8211; 2025-11-06T112123.842&Prime; align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><em><span style=\"color: #000000;\">\u00ab Puissante et g\u00e9n\u00e9reuse, cette petite sph\u00e8re de 18 cm sait mettre l\u2019ambiance telle une grande, aussi bien \u00e0 la maison que dans le jardin. Elle s\u00e9duit par sa couverture sonore \u00e9tendue facilitant son placement, la clart\u00e9 qu\u2019elle apporte aux voix et son caract\u00e8re bien tremp\u00e9 dans le grave \u00bb.<\/span><\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/11\/Design-sans-titre-2025-11-06T113441.427.png\u00a0\u00bb title_text=\u00a0\u00bbDesign sans titre &#8211; 2025-11-06T113441.427&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><em><span style=\"color: #000000;\">\u00ab THE PEARL MYUKi est une enceinte sans fil premium coh\u00e9rente. Tout d\u2019abord au niveau de sa pr\u00e9sentation avec une finition et des mat\u00e9riaux de qualit\u00e9. Le son est \u00e9quilibr\u00e9, chaleureux, ma\u00eetris\u00e9. Le calibrage audio automatique et les multiples r\u00e9glages dans l\u2019app vous permettront d\u2019obtenir le son qui vous convient. \u00bb<\/span><\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb43px||28px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||70px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0POURQUOI CHOISIR CABASSE ?<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">POURQUOI CHOISIR CABASSE ?<\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/10\/UPDATE-1.png\u00a0\u00bb title_text=\u00a0\u00bbUPDATE (1)\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb45%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">MISE \u00c0 JOUR AUTOMATIQUE\u00a0<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">MISE \u00c0 JOUR AUTOMATIQUE<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">L&rsquo;application Cabasse StreamCONTROL vous propose automatiquement des mise \u00e0 jours pour faire \u00e9voluer vos syst\u00e8mes audio.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/10\/GARANTEE-1.png\u00a0\u00bb title_text=\u00a0\u00bbGARANTEE (1)\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb45%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text content_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">GARANTIE 2 ANS\u00a0<\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">GARANTIE 2 ANS<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Tout syst\u00e8me Cabasse achet\u00e9 neuf est garantis pendant 2 ans. Pensez \u00e0 enregistrer votre enceinte<\/span><a href=\"https:\/\/www.cabasse.com\/fr\/enregistrer-un-produit\/\"> ici<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/10\/SET-1.png\u00a0\u00bb title_text=\u00a0\u00bbSET (1)\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb45%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text content_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">DEMANDEZ UN EXPERT CABASSE\u00a0<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">DEMANDEZ UN EXPERT CABASSE<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Contactez un expert Cabasse via notre service technique \/SAV en ligne et consultez aussi notre FAQ.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb24px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||||true|false\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0VOUS POURRIEZ AUSSI AIMER\u00a0<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">VOUS POURRIEZ AUSSI AIMER<\/span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/03\/TP1.mp4&Prime; module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2023\/07\/Pearl-logo.png\u00a0\u00bb title_text=\u00a0\u00bbPearl logo\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||-2px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb2px||29px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">3 Voies<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">14 \u2013 27 000 Hz<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">118 dB cr\u00eate mono \/ 124 dB cr\u00eate st\u00e9r\u00e9o<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb2px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Unique au monde, cette enceinte connect\u00e9e active Haute D\u00e9finition, concentre toute l\u2019exp\u00e9rience et la technologie de l\u2019embl\u00e9matique Sph\u00e8re au service de l\u2019\u00e9motion acoustique.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/the-pearl\/\u00a0\u00bb button_text=\u00a0\u00bbEn savoir plus\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_phone=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bb\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/03\/tpa1.mp4&Prime; module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2023\/07\/Pearl-AKOYA-logo.png\u00a0\u00bb title_text=\u00a0\u00bbPearl AKOYA logo\u00a0\u00bb url=\u00a0\u00bbhttp:\/\/Sp\u00e9cifications\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb custom_margin=\u00a0\u00bb||1px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb2px||29px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">3 Voies<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">30 \u2013 27 000 Hz<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">115 dB cr\u00eate mono \/ 121 dB cr\u00eate st\u00e9r\u00e9o<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb5px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Petite s\u0153ur de THE PEARL, l\u2019enceinte de streaming haute r\u00e9solution THE PEARL AKOYA, est \u00e0 la fois un bijou en terme de design, de technologie et de compacit\u00e9.<\/span><\/p>\n<p style=\"text-align: center;\">[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/the-pearl-akoya\/\u00a0\u00bb button_text=\u00a0\u00bbEn savoir plus\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_phone=\u00a0\u00bbSp\u00e9cifications\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bb\u00a0\u00bb button_alignment_phone=\u00a0\u00bb\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb5px\u00a0\u00bb custom_margin=\u00a0\u00bb-10px||||false|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb7px||28px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/Original-video.mp4&Prime; module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_radii=\u00a0\u00bbon|6px|6px|6px|6px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.17.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bb|300||on|||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb header_3_font=\u00a0\u00bb|300|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|69px||84px|true|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px||\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-self: center;\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0RESERVEZ UNE ECOUTE PRIVEE DANS UN CABASSE\u00a0 ACOUSTIC CENTER\u00a0<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00a0\u00bboff|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">RESERVEZ UNE ECOUTE PRIVEE DANS UN CABASSE\u00a0 ACOUSTIC CENTER<\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb19px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">Vous souhaitez vivre des \u00e9motions acoustiques immersives ?<br \/>\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\">R\u00e9servez une \u00e9coute personnalis\u00e9e aupr\u00e8s d&rsquo;un Cabasse Acoustic Center, prenez conseil aupr\u00e8s des sp\u00e9cialistes de la marque et\u00a0 choisissez votre syst\u00e8me audio id\u00e9al.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/magasins\/\u00a0\u00bb button_text=\u00a0\u00bbTrouvez votre CAC le plus proche \u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbTrouvez le CAC le plus proche \u00a0\u00bb button_text_phone=\u00a0\u00bbTrouvez le CAC le plus proche \u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb4px\u00a0\u00bb button_font=\u00a0\u00bbRoboto||||||||\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb custom_margin=\u00a0\u00bb-8px||||false|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb\u00a0\u00bb button_text_size_phone=\u00a0\u00bb\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2025\/03\/Map.png\u00a0\u00bb title_text=\u00a0\u00bbMap\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.cabasse.com\/fr\/magasins\/\u00a0\u00bb src_tablet=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2023\/03\/Fr2.png\u00a0\u00bb src_phone=\u00a0\u00bbhttps:\/\/www.cabasse.com\/wp-content\/uploads\/2023\/03\/Fr2.png\u00a0\u00bb src_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb43%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN RAPPORT COMPACIT\u00c9 \/ PERFORMANCES ACOUSTIQUES D\u2019EXCEPTION UN RAPPORT COMPACIT\u00c9 \/ PERFORMANCES ACOUSTIQUES D\u2019EXCEPTIONUltra compacte, cette nouvelle enceinte Cabasse est dot\u00e9e d\u2019un son \u00e0 la fois tr\u00e8s \u00e9quilibr\u00e9 et tr\u00e8s puissant gr\u00e2ce notamment \u00e0 ses nouveaux haut-parleurs capables de jouer jusqu\u2019\u00e0 109 dB en st\u00e9r\u00e9o : Un haut-parleur large bande DOM 45 et 2 haut-parleurs [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":245364,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-243031","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>THE PEARL MYUKI - Cabasse<\/title>\n<meta name=\"description\" content=\"La nouvelle enceinte active connect\u00e9e haute r\u00e9solution sur batterie ultra-portable, &amp; ultra-puissante de la Collection THE PEARL .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"THE PEARL MYUKI - Cabasse\" \/>\n<meta property=\"og:description\" content=\"La nouvelle enceinte active connect\u00e9e haute r\u00e9solution sur batterie ultra-portable, &amp; ultra-puissante de la Collection THE PEARL .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabasse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cabasseofficiel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T10:12:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/11\/THE-PEARL-MYUKI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CabasseFR\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/\",\"url\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/\",\"name\":\"THE PEARL MYUKI - Cabasse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cabasse.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/THE-PEARL-MYUKI.png\",\"datePublished\":\"2024-05-30T10:20:04+00:00\",\"dateModified\":\"2026-01-20T10:12:02+00:00\",\"description\":\"La nouvelle enceinte active connect\u00e9e haute r\u00e9solution sur batterie ultra-portable, & ultra-puissante de la Collection THE PEARL .\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cabasse.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/THE-PEARL-MYUKI.png\",\"contentUrl\":\"https:\\\/\\\/www.cabasse.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/THE-PEARL-MYUKI.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/fr\\\/the-pearl-myuki-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cabasse.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"THE PEARL MYUKI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cabasse.com\\\/\",\"name\":\"Cabasse\",\"description\":\"Cabasse - Acoustic Emotions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cabasse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/#organization\",\"name\":\"Cabasse\",\"url\":\"https:\\\/\\\/www.cabasse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cabasse.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-cabasse-logo-192x192-1.png\",\"contentUrl\":\"https:\\\/\\\/www.cabasse.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-cabasse-logo-192x192-1.png\",\"width\":192,\"height\":192,\"caption\":\"Cabasse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cabasse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cabasseofficiel\",\"https:\\\/\\\/x.com\\\/CabasseFR\",\"https:\\\/\\\/www.instagram.com\\\/cabasseacoustic\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCayQjMTjB3WsOZWDcsGVPAQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"THE PEARL MYUKI - Cabasse","description":"La nouvelle enceinte active connect\u00e9e haute r\u00e9solution sur batterie ultra-portable, & ultra-puissante de la Collection THE PEARL .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"THE PEARL MYUKI - Cabasse","og_description":"La nouvelle enceinte active connect\u00e9e haute r\u00e9solution sur batterie ultra-portable, & ultra-puissante de la Collection THE PEARL .","og_url":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/","og_site_name":"Cabasse","article_publisher":"https:\/\/www.facebook.com\/cabasseofficiel","article_modified_time":"2026-01-20T10:12:02+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/11\/THE-PEARL-MYUKI.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CabasseFR","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/","url":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/","name":"THE PEARL MYUKI - Cabasse","isPartOf":{"@id":"https:\/\/www.cabasse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/#primaryimage"},"image":{"@id":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/11\/THE-PEARL-MYUKI.png","datePublished":"2024-05-30T10:20:04+00:00","dateModified":"2026-01-20T10:12:02+00:00","description":"La nouvelle enceinte active connect\u00e9e haute r\u00e9solution sur batterie ultra-portable, & ultra-puissante de la Collection THE PEARL .","breadcrumb":{"@id":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/#primaryimage","url":"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/11\/THE-PEARL-MYUKI.png","contentUrl":"https:\/\/www.cabasse.com\/wp-content\/uploads\/2024\/11\/THE-PEARL-MYUKI.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.cabasse.com\/fr\/the-pearl-myuki-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cabasse.com\/"},{"@type":"ListItem","position":2,"name":"THE PEARL MYUKI"}]},{"@type":"WebSite","@id":"https:\/\/www.cabasse.com\/#website","url":"https:\/\/www.cabasse.com\/","name":"Cabasse","description":"Cabasse - Acoustic Emotions","publisher":{"@id":"https:\/\/www.cabasse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cabasse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cabasse.com\/#organization","name":"Cabasse","url":"https:\/\/www.cabasse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cabasse.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cabasse.com\/wp-content\/uploads\/2020\/04\/cropped-cabasse-logo-192x192-1.png","contentUrl":"https:\/\/www.cabasse.com\/wp-content\/uploads\/2020\/04\/cropped-cabasse-logo-192x192-1.png","width":192,"height":192,"caption":"Cabasse"},"image":{"@id":"https:\/\/www.cabasse.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cabasseofficiel","https:\/\/x.com\/CabasseFR","https:\/\/www.instagram.com\/cabasseacoustic\/","https:\/\/www.youtube.com\/channel\/UCayQjMTjB3WsOZWDcsGVPAQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/pages\/243031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/comments?post=243031"}],"version-history":[{"count":45,"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/pages\/243031\/revisions"}],"predecessor-version":[{"id":252708,"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/pages\/243031\/revisions\/252708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/media\/245364"}],"wp:attachment":[{"href":"https:\/\/www.cabasse.com\/fr\/wp-json\/wp\/v2\/media?parent=243031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}